{"id":4249,"date":"2025-01-05T20:48:00","date_gmt":"2025-01-05T20:48:00","guid":{"rendered":"https:\/\/nucleomigra.cl\/news\/el-reto-de-la-disminucion-de-las-tasas-de-natalidad-debe-situarse-en-el-centro-de-la-agenda-nacional\/"},"modified":"2026-06-24T13:28:45","modified_gmt":"2026-06-24T13:28:45","slug":"el-reto-de-la-disminucion-de-las-tasas-de-natalidad-debe-situarse-en-el-centro-de-la-agenda-nacional","status":"publish","type":"news","link":"https:\/\/nucleomigra.cl\/es\/prensa\/el-reto-de-la-disminucion-de-las-tasas-de-natalidad-debe-situarse-en-el-centro-de-la-agenda-nacional\/","title":{"rendered":"\u00abEl reto de la disminuci\u00f3n de las tasas de natalidad debe situarse en el centro de la agenda nacional\u00bb."},"content":{"rendered":"","protected":false},"featured_media":3862,"template":"","class_list":["post-4249","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/nucleomigra.cl\/es\/wp-json\/wp\/v2\/news\/4249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nucleomigra.cl\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nucleomigra.cl\/es\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":1,"href":"https:\/\/nucleomigra.cl\/es\/wp-json\/wp\/v2\/news\/4249\/revisions"}],"predecessor-version":[{"id":4484,"href":"https:\/\/nucleomigra.cl\/es\/wp-json\/wp\/v2\/news\/4249\/revisions\/4484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nucleomigra.cl\/es\/wp-json\/wp\/v2\/media\/3862"}],"wp:attachment":[{"href":"https:\/\/nucleomigra.cl\/es\/wp-json\/wp\/v2\/media?parent=4249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}